{"id":12194,"date":"2020-07-11T06:20:06","date_gmt":"2020-07-11T05:20:06","guid":{"rendered":"http:\/\/un-film-un-jour.com\/?p=12194"},"modified":"2020-09-26T09:08:44","modified_gmt":"2020-09-26T08:08:44","slug":"chained","status":"publish","type":"post","link":"https:\/\/un-film-un-jour.com\/index.php\/2020\/07\/11\/chained\/","title":{"rendered":"Chained \u2605\u2605\u2605\u2606"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium\" src=\"http:\/\/fr.web.img3.acsta.net\/r_1920_1080\/pictures\/20\/06\/04\/16\/15\/5750227.jpg\" width=\"317\" height=\"430\" \/>La quarantaine bien entam\u00e9e, Rashi est flic \u00e0 Tel Aviv. Il effectue consciencieusement son travail dans des conditions pas toujours faciles. Sous ses dehors placides, il est particuli\u00e8rement \u00e9branl\u00e9 d&rsquo;avoir \u00e9t\u00e9 mis \u00e0 pied suite \u00e0 une enqu\u00eate interne de l&rsquo;inspection des polices pour abus d&rsquo;autorit\u00e9 sur mineur.<br \/>\nRashi est mari\u00e9 \u00e0 Avigail. La jeune femme a eu une fille d&rsquo;un premier lit qui vit avec le couple. La cohabitation n&rsquo;est pas toujours fluide entre le beau-p\u00e8re et sa belle-fille. Et les difficult\u00e9s du couple \u00e0 avoir ensemble un enfant r\u00e9v\u00e8lent des tensions qui menacent de d\u00e9g\u00e9n\u00e9rer.<\/p>\n<p><em>Chained<\/em> est un film \u00e9prouvant. De la premi\u00e8re sc\u00e8ne &#8211; o\u00f9 l&rsquo;on voit Rashi et son acolyte interpeler un p\u00e8re violent &#8211; jusqu&rsquo;\u00e0 la derni\u00e8re &#8211; dont on ne dira rien &#8211; on sera scotch\u00e9 \u00e0 son fauteuil et tr\u00e8s mal \u00e0 l&rsquo;aise. On s&rsquo;\u00e9tonne d&rsquo;ailleurs que la commission de classification ait d\u00e9livr\u00e9 un visa tous publics sans aucun avertissement &#8211; l\u00e0 o\u00f9 l&rsquo;inoffensif <a href=\"https:\/\/un-film-un-jour.com\/index.php\/2020\/07\/10\/lucky-strike\/\"><em>Lucky Strike<\/em><\/a> que j&rsquo;ai chroniqu\u00e9 hier \u00e9copait d&rsquo;une s\u00e9v\u00e8re interdiction aux moins de douze ans.<\/p>\n<p><em>Chained<\/em> est construit selon un proc\u00e9d\u00e9 simple mais terriblement efficace : sans aucun temps mort, sans aucune respiration, chaque sc\u00e8ne raconte jusqu&rsquo;\u00e0 l&rsquo;\u00e9puisement une dispute, plus ou moins violente. C&rsquo;est d&rsquo;abord, on l&rsquo;a dit, Rashi dans son m\u00e9tier, qui arr\u00eate un p\u00e8re de famille ou qui proc\u00e8de \u00e0 la fouille d&rsquo;adolescents suspect\u00e9s de vendre de la drogue. C&rsquo;est ensuite Rashi et sa belle-fille avec laquelle il se montre trop protecteur, lui interdisant toute sortie, ce qui stimule en retour l&rsquo;esprit de rebellion de l&rsquo;adolescente. C&rsquo;est enfin Rashi et Avigail dans leur PMA infructueuse et dont le couple se d\u00e9fait inexorablement.<\/p>\n<p>Rashi est au centre de chacune de ses disputes, qu&rsquo;il les provoque ou qu&rsquo;il les subisse. Le personnage est ambivalent, servi par l&rsquo;interpr\u00e9tation impeccable de Eran Naim. Son physique, de gros nounours tendre, est plut\u00f4t rassurant ; mais on sent en lui une violence qui ne demande qu&rsquo;\u00e0 \u00e9clater. Sans \u00eatre un saint, il n&rsquo;est ni un flic ripoux, ni un beau-p\u00e8re abusif ni un mari violent. La richesse du personnage vient pr\u00e9cis\u00e9ment de son ambigu\u00eft\u00e9.<\/p>\n<p><em>Chained<\/em> est le premier volet d&rsquo;un diptyque. <a href=\"https:\/\/un-film-un-jour.com\/index.php\/2020\/07\/21\/beloved\/\"><em>Beloved<\/em> <\/a>sortira sur les \u00e9crans mercredi prochain. Il est film\u00e9 du point de vue d&rsquo;Avigail. Je courrai le voir.<\/p>\n<p><a href=\"http:\/\/www.allocine.fr\/video\/player_gen_cmedia=19588350&amp;cfilm=270600.html\">La bande-annonce<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La quarantaine bien entam\u00e9e, Rashi est flic \u00e0 Tel Aviv. Il effectue consciencieusement son travail dans des conditions pas toujours faciles. Sous ses dehors placides, il est particuli\u00e8rement \u00e9branl\u00e9 d&rsquo;avoir \u00e9t\u00e9 mis \u00e0 pied suite \u00e0 une enqu\u00eate interne de l&rsquo;inspection des polices pour abus d&rsquo;autorit\u00e9 sur mineur. Rashi est mari\u00e9 \u00e0 Avigail. La jeune [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61,69],"tags":[],"class_list":["post-12194","post","type-post","status-publish","format-standard","hentry","category-films-sortis-en-2020","category-films-sortis-en-juillet-2020"],"_links":{"self":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/12194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/comments?post=12194"}],"version-history":[{"count":5,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/12194\/revisions"}],"predecessor-version":[{"id":12762,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/12194\/revisions\/12762"}],"wp:attachment":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/media?parent=12194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/categories?post=12194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/tags?post=12194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}