{"id":13919,"date":"2021-04-18T09:03:53","date_gmt":"2021-04-18T08:03:53","guid":{"rendered":"http:\/\/un-film-un-jour.com\/?p=13919"},"modified":"2021-04-18T09:42:04","modified_gmt":"2021-04-18T08:42:04","slug":"40-ans-toujours-dans-le-flow","status":"publish","type":"post","link":"https:\/\/un-film-un-jour.com\/index.php\/2021\/04\/18\/40-ans-toujours-dans-le-flow\/","title":{"rendered":"40 ans, toujours dans le flow \u2605\u2605\u2606\u2606"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium\" src=\"https:\/\/fr.web.img6.acsta.net\/r_1920_1080\/pictures\/20\/08\/27\/11\/12\/2954099.jpg\" width=\"317\" height=\"430\" \/>Radha Blank est en pleine crise de la quarantaine. Voil\u00e0 plus de dix ans qu&rsquo;elle n&rsquo;a pas r\u00e9ussi \u00e0 concr\u00e9tiser les espoirs que ses premi\u00e8res \u0153uvres th\u00e9\u00e2trales avaient fait na\u00eetre malgr\u00e9 les efforts que d\u00e9ploie son agent et ami d&rsquo;enfance. C\u00e9libataire, en surpoids, elle vit \u00e0 Harlem dans un appartement exigu et peine \u00e0 faire le deuil de sa m\u00e8re qui vient de mourir. La production de sa prochaine pi\u00e8ce l&rsquo;oblige \u00e0 des compromis auxquels elle se refuse. En attendant, elle vivote en donnant des cours de th\u00e9\u00e2tre dans un lyc\u00e9e dont les \u00e9l\u00e8ves lui m\u00e8nent la vie dure.<\/p>\n<p>L&rsquo;autobiographie de l&rsquo;auteur en proie au doute cr\u00e9atif est un genre \u00e9cul\u00e9. C&rsquo;est, tout bien consid\u00e9r\u00e9, assez logique : les auteurs qui cherchent d\u00e9sesp\u00e9r\u00e9ment un sujet d&rsquo;inspiration finissent tous immanquablement par \u00e9crire sur leur exp\u00e9rience imm\u00e9diate de l&rsquo;angoisse de la page blanche. C&rsquo;est aussi un genre dangereux qui court les risques alternatifs ou cumulatifs du nombrilisme, de la complaisance et de l&rsquo;insignifiance : quoi de plus \u00e9gocentrique et de plus ennuyeux qu&rsquo;un auteur en train de raconter le vide de sa vie ?<\/p>\n<p>Radha Blank parvient avec beaucoup de pudeur \u00e0 \u00e9viter ces emb\u00fbches.<br \/>\nCertes son autobiographie ne bouleverse pas les canons du genre et ne r\u00e9serve gu\u00e8re de surprises. Comme on s&rsquo;y attendait, il n&rsquo;y a pas un plan qui ne la montre, seule chez elle, sur le chemin de son lyc\u00e9e, avec ses \u00e9l\u00e8ves, en compagnie de son agent ou bien encore durant les r\u00e9p\u00e9titions de sa pi\u00e8ce. Son omnipr\u00e9sence pourtant n&rsquo;est pas envahissante ; car elle fait preuve de tant d&rsquo;humour, de tant de lucidit\u00e9 qu&rsquo;on ne peut tr\u00e8s vite que s&rsquo;attacher \u00e0 elle. Les dialogues sont cisel\u00e9s. Aucun ne provoque d&rsquo;\u00e9clat de rire ; mais tous font na\u00eetre une \u00e9motion.<\/p>\n<p>Tourn\u00e9 dans un noir et blanc velout\u00e9, en 35mm, <em>40 ans, toujours dans le flow<\/em> (traduction calamiteuse de <em>The Forty-Year-Old Version<\/em>) se d\u00e9roule \u00e0 Harlem, dans le nord de Manhattan. Il r\u00e9ussit le pari paradoxal de filmer New York avec \u00e9l\u00e9gance sans en montrer aucun des clich\u00e9s caract\u00e9ristiques.<\/p>\n<p>L&rsquo;autobiographie de Radha Blank est aussi l&rsquo;histoire d&rsquo;une h\u00e9sitation et d&rsquo;une bifurcation : Radha continuera-t-elle \u00e0 \u00e9crire des pi\u00e8ces de th\u00e9\u00e2tre en usant jusqu&rsquo;\u00e0 la corde des sujets qu&rsquo;elle et d&rsquo;autres ont d\u00e9j\u00e0 explor\u00e9s ? ou osera-t-elle avec le beau D, malgr\u00e9 leur diff\u00e9rence d&rsquo;\u00e2ge, slamer ses textes sur une musique de rap ? La conclusion est sans surprise ; mais elle sonnera comme un message d&rsquo;espoir pour tous ceux qui traversent la crise de la quarantaine en d\u00e9sesp\u00e9rant de se r\u00e9inventer.<\/p>\n<p><a href=\"https:\/\/www.allocine.fr\/video\/player_gen_cmedia=19589671&amp;cfilm=276203.html\">La bande-annonce<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Radha Blank est en pleine crise de la quarantaine. Voil\u00e0 plus de dix ans qu&rsquo;elle n&rsquo;a pas r\u00e9ussi \u00e0 concr\u00e9tiser les espoirs que ses premi\u00e8res \u0153uvres th\u00e9\u00e2trales avaient fait na\u00eetre malgr\u00e9 les efforts que d\u00e9ploie son agent et ami d&rsquo;enfance. C\u00e9libataire, en surpoids, elle vit \u00e0 Harlem dans un appartement exigu et peine \u00e0 faire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61,74,54],"tags":[],"class_list":["post-13919","post","type-post","status-publish","format-standard","hentry","category-films-sortis-en-2020","category-films-sortis-en-octobre-2020","category-inedit-en-salles"],"_links":{"self":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/13919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/comments?post=13919"}],"version-history":[{"count":4,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/13919\/revisions"}],"predecessor-version":[{"id":14126,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/13919\/revisions\/14126"}],"wp:attachment":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/media?parent=13919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/categories?post=13919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/tags?post=13919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}