{"id":14806,"date":"2021-07-08T06:47:44","date_gmt":"2021-07-08T05:47:44","guid":{"rendered":"http:\/\/un-film-un-jour.com\/?p=14806"},"modified":"2021-07-08T08:08:45","modified_gmt":"2021-07-08T07:08:45","slug":"annette","status":"publish","type":"post","link":"https:\/\/un-film-un-jour.com\/index.php\/2021\/07\/08\/annette\/","title":{"rendered":"Annette \u2605\u2606\u2606\u2606"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium\" src=\"https:\/\/fr.web.img2.acsta.net\/r_1920_1080\/pictures\/21\/06\/01\/12\/08\/4034608.jpg\" width=\"317\" height=\"430\" \/>Henry (Adam Driver), un com\u00e9dien de <em>stand-up<\/em> \u00e0 l&rsquo;humour f\u00e9roce, et Anne (Marion Cotillard), une cantatrice fran\u00e7aise, forment l&rsquo;un des couples les plus glamours et les plus adul\u00e9s de Hollywood. Ils ont bient\u00f4t ensemble une fille qu&rsquo;ils pr\u00e9nomment Annette. Mais le comportement de Henry change imperceptiblement&#8230;<\/p>\n<p>Le nouveau film de Leos Carax est sans doute le plus attendu du moment. On a vu tourner sa bande-annonce pendant tout le mois de juin. Il fait l&rsquo;ouverture du festival de Cannes. Il constitue seulement le sixi\u00e8me film de ce r\u00e9alisateur hors normes, aussi fantasque qu&rsquo;exigeant, r\u00e9v\u00e9l\u00e9 dans les ann\u00e9es quatre-vingts par l&rsquo;\u00e9nergie et la po\u00e9sie de ses deux premiers films <em>Boy Meets Girl <\/em>et <em>Mauvais Sang<\/em> avant de se br\u00fbler les ailes dans le pharaonique <em>Amants du Pont-Neuf<\/em>.<\/p>\n<p>Reconnaissons honn\u00eatement que cette impatience n&rsquo;\u00e9tait pas vaine &#8211; m\u00eame si la bande-annonce, comme souvent h\u00e9las, a d\u00e9j\u00e0 d\u00e9voil\u00e9 l&rsquo;essentiel. Somptueux op\u00e9ra rock au lyrisme revendiqu\u00e9, <em>Annette<\/em> nous en met plein les mirettes pendant plus de deux heures. Leos Carax r\u00e9ussit, avec une audace inentam\u00e9e, \u00e0 revisiter toutes les formes du cin\u00e9ma &#8211; la com\u00e9die musicale, le drame shakespearien, le thriller, le film fantastique &#8211; \u00e0 les malaxer et \u00e0 faire na\u00eetre une forme nouvelle d&rsquo;une vibrante \u00e9nergie.<\/p>\n<p>Mais c&rsquo;est bien l\u00e0 le seul atout d&rsquo;un film qui devient tr\u00e8s vite d\u00e9sagr\u00e9able \u00e0 force de pr\u00e9tention. On a l&rsquo;impression qu&rsquo;\u00e0 chaque plan, Leos Carax veut nous d\u00e9montrer qu&rsquo;il est toujours un cin\u00e9aste qui compte, capable de nous \u00e9tonner. Tant d&rsquo;application m&rsquo;as-tu-vu dans la d\u00e9monstration devient h\u00e9las vite contreproductif. Surtout si elle ne s&rsquo;accompagne pas d&rsquo;un minimum de sens. Or, de sens, Annette n&rsquo;en a gu\u00e8re. Quel en est le sujet ? un homme qui sombre dans la folie meurtri\u00e8re ? un couple que la c\u00e9l\u00e9brit\u00e9 \u00e9touffe ? une enfant prodige qui trouve le courage de rompre avec son p\u00e8re toxique ? les trois \u00e0 la fois ?<\/p>\n<p>On a l&rsquo;impression que Carax se d\u00e9sint\u00e9resse de l&rsquo;histoire qu&rsquo;il raconte, obnubil\u00e9 qu&rsquo;il est par la perfection formelle de chacune des sc\u00e8nes qui la composent. C&rsquo;est peut-\u00eatre une fa\u00e7on efficace d&rsquo;\u00e9crire un op\u00e9ra &#8211; et <em>Annette<\/em>, gr\u00e2ce \u00e0 la musique ind\u00e9modable des <em>Sparks<\/em>, contient en effet quelques sc\u00e8nes d&rsquo;anthologie. Mais ce n&rsquo;est pas la meilleure pour r\u00e9aliser un film.<\/p>\n<p><a href=\"https:\/\/www.allocine.fr\/video\/player_gen_cmedia=19591946&amp;cfilm=235632.html\">La bande-annonce<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Henry (Adam Driver), un com\u00e9dien de stand-up \u00e0 l&rsquo;humour f\u00e9roce, et Anne (Marion Cotillard), une cantatrice fran\u00e7aise, forment l&rsquo;un des couples les plus glamours et les plus adul\u00e9s de Hollywood. Ils ont bient\u00f4t ensemble une fille qu&rsquo;ils pr\u00e9nomment Annette. Mais le comportement de Henry change imperceptiblement&#8230; Le nouveau film de Leos Carax est sans doute [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72,83],"tags":[],"class_list":["post-14806","post","type-post","status-publish","format-standard","hentry","category-films-sortis-en-2021","category-films-sortis-en-juillet-2021"],"_links":{"self":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/14806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/comments?post=14806"}],"version-history":[{"count":4,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/14806\/revisions"}],"predecessor-version":[{"id":14817,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/14806\/revisions\/14817"}],"wp:attachment":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/media?parent=14806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/categories?post=14806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/tags?post=14806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}