{"id":16089,"date":"2022-01-21T09:25:01","date_gmt":"2022-01-21T08:25:01","guid":{"rendered":"http:\/\/un-film-un-jour.com\/?p=16089"},"modified":"2022-01-21T09:50:12","modified_gmt":"2022-01-21T08:50:12","slug":"little-palestine-journal-dun-siege","status":"publish","type":"post","link":"https:\/\/un-film-un-jour.com\/index.php\/2022\/01\/21\/little-palestine-journal-dun-siege\/","title":{"rendered":"Little Palestine, journal d&rsquo;un si\u00e8ge \u2605\u2606\u2606\u2606"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium\" src=\"https:\/\/fr.web.img6.acsta.net\/r_1920_1080\/pictures\/21\/12\/02\/11\/26\/1618475.jpg\" width=\"317\" height=\"430\" \/>Le camp de Yabrouk, au sud de Damas, accueillait des dizaines de milliers de r\u00e9fugi\u00e9s palestiniens depuis 1957. Les Nations-Unies en assuraient la gestion. Au lendemain des printemps arabes, l&rsquo;arm\u00e9e de Bachar el-Assad prit le pr\u00e9texte de la pr\u00e9sence de groupuscules rebelles pour en verrouiller tous les acc\u00e8s. Des milliers de r\u00e9fugi\u00e9s y furent pris au pi\u00e8ge avant que Daesh s&rsquo;en empare en 2015. Pour le lib\u00e9rer, Damas, aid\u00e9 des bombardiers russes, le rasa en 2018. Ses habitants s&rsquo;enfuirent et se dispers\u00e8rent tant bien que mal \u00e0 l&rsquo;\u00e9tranger.<br \/>\nMilitant du Fatah, Abdallah Al-Khatib faisait partie de ces r\u00e9fugi\u00e9s. Install\u00e9 aujourd&rsquo;hui en Allemagne, il a rassembl\u00e9 les diff\u00e9rents enregistrements r\u00e9alis\u00e9s pendant le si\u00e8ge, souvent \u00e0 partir de simples t\u00e9l\u00e9phones portables. Il les a rassembl\u00e9s dans un documentaire qui raconte une page m\u00e9connue de la guerre de Syrie.<\/p>\n<p>Il est difficile de porter un jugement distanci\u00e9 sur <em>Little Palestine<\/em>.<\/p>\n<p>Ses images saisies sur le vif sont, comme celles de <a href=\"https:\/\/un-film-un-jour.com\/index.php\/2019\/10\/15\/pour-sama\/\"><em>Pour Sama<\/em><\/a> ou celles de <a href=\"https:\/\/un-film-un-jour.com\/index.php\/2019\/04\/01\/still-recording\/\"><em>Still Recording<\/em><\/a> vol\u00e9es durant le si\u00e8ge d&rsquo;Alep, bouleversantes. Quelques sc\u00e8nes laisseront un souvenir durable : un nouveau-n\u00e9 cadav\u00e9rique t\u00e9tant un biberon de lait coup\u00e9 d&rsquo;eau, une foule d&rsquo;apocalypse qui se presse \u00e0 un point de distribution, des enfants joyeux qui confient leurs r\u00eaves impossibles (manger du pain, revoir leur fr\u00e8re mort) en riant, une fillette qui cueille de l&rsquo;herbe pour se nourrir en tenant un discours d&rsquo;une maturit\u00e9 qu&rsquo;elle est bien trop jeune pour avoir d\u00e9j\u00e0&#8230;.<\/p>\n<p>Pour autant, tout cela fait-il du cin\u00e9ma ? Peut-on consid\u00e9rer que l&rsquo;accumulation de vid\u00e9os tremblotantes et crachotantes, film\u00e9es avec un t\u00e9l\u00e9phone portable, suffit \u00e0 faire un film ? cette accumulation permet-elle de raconter l&rsquo;attente \u00e9molliente, l&rsquo;anxi\u00e9t\u00e9, la faim qui tenaille ?<\/p>\n<p><a href=\"https:\/\/www.allocine.fr\/video\/player_gen_cmedia=19595042&amp;cfilm=292439.html\">La bande-annonce<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le camp de Yabrouk, au sud de Damas, accueillait des dizaines de milliers de r\u00e9fugi\u00e9s palestiniens depuis 1957. Les Nations-Unies en assuraient la gestion. Au lendemain des printemps arabes, l&rsquo;arm\u00e9e de Bachar el-Assad prit le pr\u00e9texte de la pr\u00e9sence de groupuscules rebelles pour en verrouiller tous les acc\u00e8s. Des milliers de r\u00e9fugi\u00e9s y furent pris [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88,89],"tags":[],"class_list":["post-16089","post","type-post","status-publish","format-standard","hentry","category-films-sortis-en-2022","category-films-sortis-en-janvier-2022"],"_links":{"self":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/16089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/comments?post=16089"}],"version-history":[{"count":4,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/16089\/revisions"}],"predecessor-version":[{"id":16100,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/16089\/revisions\/16100"}],"wp:attachment":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/media?parent=16089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/categories?post=16089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/tags?post=16089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}