{"id":17231,"date":"2022-07-21T06:40:02","date_gmt":"2022-07-21T05:40:02","guid":{"rendered":"http:\/\/un-film-un-jour.com\/?p=17231"},"modified":"2022-07-21T08:02:21","modified_gmt":"2022-07-21T07:02:21","slug":"lesprit-sacre","status":"publish","type":"post","link":"https:\/\/un-film-un-jour.com\/index.php\/2022\/07\/21\/lesprit-sacre\/","title":{"rendered":"L&rsquo;Esprit sacr\u00e9 \u2605\u2606\u2606\u2606"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium\" src=\"https:\/\/fr.web.img2.acsta.net\/r_1920_1080\/pictures\/22\/03\/31\/13\/53\/4449116.jpg\" width=\"317\" height=\"430\" \/>La petite ville d&rsquo;Elche en Espagne est traumatis\u00e9e par la disparition de la jeune Vanessa. Pendant ce temps, l&rsquo;association UFO-Levante, qui r\u00e9unit quelques ufologues d\u00e9jant\u00e9s, organise la succession de son leader, Julio, qui vient de d\u00e9c\u00e9der brutalement. Jos\u00e9 Manuel, l&rsquo;oncle de Vanessa, un membre actif d&rsquo;UFO-Levante, entend mener \u00e0 bien avec Veronica, la s\u0153ur jumelle de Vanessa, l&rsquo;entreprise engag\u00e9e par Julio.<\/p>\n<p><em>L&rsquo;Esprit sacr\u00e9<\/em> est un film d\u00e9concertant. Son th\u00e8me pourrait laisser augurer une com\u00e9die loufoque mettant en sc\u00e8ne quelques cingl\u00e9s pas franchement sympathiques unis par des croyances insens\u00e9es. Mais le film prend une autre voie plus d\u00e9routante. \u00c0 la com\u00e9die, il pr\u00e9f\u00e8re la trag\u00e9die. \u00c0 l&rsquo;ambiance joyeusement d\u00e9cal\u00e9e, il pr\u00e9f\u00e8re installer lentement un malaise qui culminera dans la r\u00e9v\u00e9lation qui accompagnera l&rsquo;\u00e9pilogue tristement pressenti.<\/p>\n<p>Ce malaise n&rsquo;a rien de tr\u00e8s agr\u00e9able. D&rsquo;autant qu&rsquo;il s&rsquo;\u00e9tire interminablement sans que rien dans le sc\u00e9nario ne vienne en relancer le rythme. Il n&rsquo;a rien de tr\u00e8s int\u00e9ressant non plus. Qu&rsquo;apprend-on sur le conspirationnisme ? sur la surm\u00e9diatisation ? Les cinq paum\u00e9s d&rsquo;UFO-Levante auraient pu \u00eatre dr\u00f4les. Ils ne le sont pas. Ils auraient pu \u00eatre touchants. Ils ne le sont pas non plus. Ces minables, \u00e0 commencer par le premier d&rsquo;entre eux, Jos\u00e9 Manuel, qui semblent d\u00e9pourvus de tout sens moral, sont tout bonnement d\u00e9testables. Et avec eux ce film dont on peine \u00e0 comprendre l&rsquo;objet.<\/p>\n<p><a href=\"https:\/\/www.allocine.fr\/video\/player_gen_cmedia=19596975&amp;cfilm=284469.html\">La bande-annonce<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La petite ville d&rsquo;Elche en Espagne est traumatis\u00e9e par la disparition de la jeune Vanessa. Pendant ce temps, l&rsquo;association UFO-Levante, qui r\u00e9unit quelques ufologues d\u00e9jant\u00e9s, organise la succession de son leader, Julio, qui vient de d\u00e9c\u00e9der brutalement. Jos\u00e9 Manuel, l&rsquo;oncle de Vanessa, un membre actif d&rsquo;UFO-Levante, entend mener \u00e0 bien avec Veronica, la s\u0153ur jumelle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88,96],"tags":[],"class_list":["post-17231","post","type-post","status-publish","format-standard","hentry","category-films-sortis-en-2022","category-films-sortis-en-juillet-2022"],"_links":{"self":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/17231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/comments?post=17231"}],"version-history":[{"count":8,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/17231\/revisions"}],"predecessor-version":[{"id":17271,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/17231\/revisions\/17271"}],"wp:attachment":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/media?parent=17231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/categories?post=17231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/tags?post=17231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}