{"id":2231,"date":"2016-08-29T06:42:06","date_gmt":"2016-08-29T05:42:06","guid":{"rendered":"http:\/\/un-film-un-jour.com\/?p=2231"},"modified":"2016-08-29T08:04:29","modified_gmt":"2016-08-29T07:04:29","slug":"toni-erdmann","status":"publish","type":"post","link":"https:\/\/un-film-un-jour.com\/index.php\/2016\/08\/29\/toni-erdmann\/","title":{"rendered":"Toni Erdmann \u2605\u2605\u2606\u2606"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium\" src=\"http:\/\/fr.web.img6.acsta.net\/r_1920_1080\/pictures\/16\/07\/18\/16\/55\/166709.jpg\" alt=\"\" width=\"317\" height=\"430\" \/>Depuis sa sortie \u00e0 Cannes o\u00f9 il avait re\u00e7u un accueil enthousiaste, <em>Toni Erdmann<\/em> divise les spectateurs. La majorit\u00e9 salue une \u0153uvre hors nome, loufoque et attachante. La minorit\u00e9 crie \u00e0 l&rsquo;imposture. De quel c\u00f4t\u00e9 vous classerez-vous ?<\/p>\n<p>Il faut sans doute reconna\u00eetre \u00e0 <em>Toni Erdmann<\/em> une certaine originalit\u00e9. Moins dans le sujet qu&rsquo;il traite que dans sa mani\u00e8re de le faire.<\/p>\n<p>Le sujet ? Il y en a deux : la relation p\u00e8re-fille et le capitalisme en Roumanie.<br \/>\nLa relation p\u00e8re-fille file a priori sur un chemin trac\u00e9 d&rsquo;avance. Winfried, la soixantaine, professeur de musique dans un coll\u00e8ge allemand, n&rsquo;a plus gu\u00e8re de contacts avec Ines, sa fille partie travailler comme consultante en Roumanie. Sans crier gare, il va l&rsquo;y rejoindre, d\u00e9boulant dans sa vie comme un chien dans un jeu de quilles sous l&rsquo;identit\u00e9 d&rsquo;un fantasque Toni Erdmann, tour \u00e0 tour coach, ambassadeur d&rsquo;Allemagne, peintre sur \u0153ufs et consultant dans l&rsquo;industrie p\u00e9troli\u00e8re.<br \/>\nLa peinture du capitalisme sans \u00e2me qui corrompt \u00e0 la fois un pays et l&rsquo;\u00e2me de ceux qui l&rsquo;exploite constitue, lui aussi, un th\u00e8me rabattu.<\/p>\n<p>Mais c&rsquo;est dans la fa\u00e7on de traiter ces deux th\u00e8mes que Maren Ade, jeune et prometteuse r\u00e9alisatrice allemande, surprend et \u00e9meut.<br \/>\nR\u00e9sumer la relation de Winfried et d&rsquo;Ines \u00e0 leur r\u00e9conciliation serait appauvrir un couple p\u00e8re-fille dont deux heures quarante de film permettent de comprendre la complexit\u00e9. Il n&rsquo;y a pas d&rsquo;un c\u00f4t\u00e9 un p\u00e8re loufoque et de l&rsquo;autre une fille drogu\u00e9e de travail. L&rsquo;un et l&rsquo;autre ont leurs qualit\u00e9s et leurs d\u00e9fauts. Winfried cache derri\u00e8re sa bouffonnerie une compr\u00e9hension tr\u00e8s fine de l&rsquo;\u00e9tat de sa fille ; la duret\u00e9 d&rsquo;Ines se fissure au fil du film.<br \/>\nC&rsquo;est peut-\u00eatre la peinture de la Roumanie moderne qui m&rsquo;a le plus int\u00e9ress\u00e9 dans ce film, d&rsquo;autant qu&rsquo;elle est pass\u00e9e sous silence dans les critiques que j&rsquo;ai pu lire. <em>Toni Erdmann<\/em> la d\u00e9crit comme le terrain de chasse d&rsquo;une faune cosmopolite de consultants plurilingues (on parle beaucoup de langues dans <em>Toni Erdmann<\/em> &#8211; l&rsquo;allemand, l&rsquo;anglais, le fran\u00e7ais &#8211; mais quasiment pas le roumain). C&rsquo;est un pays qui est \u00e0 la fois dans l&rsquo;UE &#8211; les directives s&rsquo;y appliquent et un personnage annonce qu&rsquo;il a remerci\u00e9 Van Rompuy d&rsquo;avoir permis son adh\u00e9sion &#8211; mais qui se situe encore \u00e0 ses marches. J&rsquo;ai particuli\u00e8rement \u00e9t\u00e9 \u00e9mue par le personnage d&rsquo;Anca, la jeune assistante d&rsquo;Ines, multidipl\u00f4m\u00e9e et ravissante, pr\u00eate \u00e0 accepter toutes les humiliations pour conserver son emploi.<\/p>\n<p><a href=\"http:\/\/www.allocine.fr\/video\/player_gen_cmedia=19564121&amp;cfilm=228026.html\">La bande-annonce<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis sa sortie \u00e0 Cannes o\u00f9 il avait re\u00e7u un accueil enthousiaste, Toni Erdmann divise les spectateurs. La majorit\u00e9 salue une \u0153uvre hors nome, loufoque et attachante. La minorit\u00e9 crie \u00e0 l&rsquo;imposture. De quel c\u00f4t\u00e9 vous classerez-vous ? Il faut sans doute reconna\u00eetre \u00e0 Toni Erdmann une certaine originalit\u00e9. Moins dans le sujet qu&rsquo;il traite [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,16],"tags":[],"class_list":["post-2231","post","type-post","status-publish","format-standard","hentry","category-films-sortis-en-2016","category-films-sortis-en-aout-2016"],"_links":{"self":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/2231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/comments?post=2231"}],"version-history":[{"count":6,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/2231\/revisions"}],"predecessor-version":[{"id":2329,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/2231\/revisions\/2329"}],"wp:attachment":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/media?parent=2231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/categories?post=2231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/tags?post=2231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}