{"id":25861,"date":"2025-05-13T07:33:13","date_gmt":"2025-05-13T06:33:13","guid":{"rendered":"https:\/\/un-film-un-jour.com\/?p=25861"},"modified":"2025-05-13T07:33:21","modified_gmt":"2025-05-13T06:33:21","slug":"un-monde-merveilleux","status":"publish","type":"post","link":"https:\/\/un-film-un-jour.com\/index.php\/2025\/05\/13\/un-monde-merveilleux\/","title":{"rendered":"Un monde merveilleux \u2605\u2606\u2606\u2606"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium\" src=\"https:\/\/fr.web.img4.acsta.net\/r_1920_1080\/img\/6f\/27\/6f277525d6b02c96bd480c3406764fcd.jpg\" width=\"347\" height=\"430\" \/><\/p>\n<p>Dans un futur \u00ab\u00a0un peu trop proche\u00a0\u00bb, la robotique a envahi notre quotidien. Des robots intelligents assument des fonctions de plus en plus nombreuses : l&rsquo;assistance m\u00e9nag\u00e8re, la garde des personnes \u00e2g\u00e9es, l&rsquo;\u00e9ducation&#8230; Max (Blanche Gradin), est une professeur agr\u00e9g\u00e9e mise au ch\u00f4mage par un robot. Elle \u00e9l\u00e8ve seule sa fille Paula, neuf ans. Hostile \u00e0 la robotisation de la soci\u00e9t\u00e9, elle vit de petites combines. Mais, quand sa fille lui est retir\u00e9e, Max n&rsquo;a d&rsquo;autre solution que de s&rsquo;adjoindre l&rsquo;aide d&rsquo;un robot T.0 pour retrouver sa trace.<\/p>\n<p><em>Un monde merveilleux<\/em> est un film burlesque qui repose tout entier sur l&rsquo;humour grin\u00e7ant de Blanche Gardin. Il imagine un futur proche qui ressemble beaucoup au n\u00f4tre sinon que les robots y occupent, pour le meilleur et pour le pire, une place plus grande. Il imagine \u00e9galement, ce qui semble parfaitement cr\u00e9dible, que cette robotisation suscite en m\u00eame temps engouement et r\u00e9sistance.<\/p>\n<p>La subtilit\u00e9 du film r\u00e9side dans son absence de manich\u00e9isme. Max ne se r\u00e9duit pas \u00e0 sa robophobie. La complicit\u00e9 qu&rsquo;elle noue avec T.0, un vieux robot sujet aux pannes (dans la peau duquel se sont gliss\u00e9es deux actrices Ang\u00e9lique Faugi\u00e8re et Lucie Guien), l&rsquo;a fait lentement \u00e9voluer.<\/p>\n<p>L&rsquo;humour triste de Blanche Gardin fait souvent mouche. Mais il ne suffit pas \u00e0 pimenter un film bien fade au parfum de t\u00e9l\u00e9film sponsoris\u00e9 par la r\u00e9gion des Pays de la Loire (on reconna\u00eet les paysages de la presqu&rsquo;\u00eele de Gu\u00e9rande). Il aurait fallu l&rsquo;audace d&rsquo;un Quentin Dupieux pour ajouter au sc\u00e9nario bien sage la touche de fantaisie qui manque \u00e0 ce <em>Monde merveilleux<\/em>.<\/p>\n<p><a href=\"https:\/\/www.allocine.fr\/video\/player_gen_cmedia=20612576&amp;cfilm=317519.html\">La bande-annonce<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un futur \u00ab\u00a0un peu trop proche\u00a0\u00bb, la robotique a envahi notre quotidien. Des robots intelligents assument des fonctions de plus en plus nombreuses : l&rsquo;assistance m\u00e9nag\u00e8re, la garde des personnes \u00e2g\u00e9es, l&rsquo;\u00e9ducation&#8230; Max (Blanche Gradin), est une professeur agr\u00e9g\u00e9e mise au ch\u00f4mage par un robot. Elle \u00e9l\u00e8ve seule sa fille Paula, neuf ans. Hostile [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[129,134],"tags":[],"class_list":["post-25861","post","type-post","status-publish","format-standard","hentry","category-films-sortis-en-2025","category-films-sortis-en-mai-2025"],"_links":{"self":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/25861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/comments?post=25861"}],"version-history":[{"count":3,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/25861\/revisions"}],"predecessor-version":[{"id":25865,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/25861\/revisions\/25865"}],"wp:attachment":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/media?parent=25861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/categories?post=25861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/tags?post=25861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}