{"id":26029,"date":"2025-06-05T08:06:16","date_gmt":"2025-06-05T07:06:16","guid":{"rendered":"https:\/\/un-film-un-jour.com\/?p=26029"},"modified":"2025-06-05T09:17:22","modified_gmt":"2025-06-05T08:17:22","slug":"rouge-midi-1985","status":"publish","type":"post","link":"https:\/\/un-film-un-jour.com\/index.php\/2025\/06\/05\/rouge-midi-1985\/","title":{"rendered":"Rouge Midi (1985) \u2605\u2605\u2606\u2606"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium\" src=\"https:\/\/media.senscritique.com\/media\/000015669692\/0\/rouge_midi.jpg\" width=\"347\" height=\"430\" \/><\/p>\n<p><em>Rouge Midi<\/em> raconte l&rsquo;histoire d&rsquo;une famille italienne arriv\u00e9e par le train \u00e0 L&rsquo;Estaque dans la banlieue de Marseille dans les ann\u00e9es vingt et de sa descendance sur quatre g\u00e9n\u00e9rations. Leur fille Maggiorina (Ariane Ascaride), employ\u00e9e \u00e0 la cimenterie, rencontrera J\u00e9r\u00f4me (G\u00e9rard Meylan), un chauffeur de ma\u00eetre, et traversera avec lui le Front populaire et l&rsquo;Occupation. Leur ami Mindou, secr\u00e8tement \u00e9pris de Maggiorina, est prox\u00e9n\u00e8te et a mis sur le trottoir Ginette en lui faisant miroiter une carri\u00e8re d&rsquo;artiste. Maggiorina et J\u00e9r\u00f4me ont deux enfants, Marie et Pierre qui grandiront pendant les Trente Glorieuses. Pierre fait des \u00e9tudes et aura un fils, Sauveur (G\u00e9rard Meylan encore lui), qui, devenu adulte, h\u00e9site \u00e0 quitter Marseille.<\/p>\n<p>Une <a href=\"https:\/\/www.lafilmotheque.fr\/evenements\/linvitee-du-mois-robert-guediguian\/\">r\u00e9trospective<\/a> est consacr\u00e9e cette semaine \u00e0 la Filmoth\u00e8que du Quartier latin \u00e0 Robert Gu\u00e9diguian qui viendra chaque soir pr\u00e9senter ses films. C&rsquo;est l&rsquo;occasion de voir ou de revoir quelques p\u00e9pites rares comme ce film-ci, son deuxi\u00e8me, tourn\u00e9 en 1984 et sorti l&rsquo;ann\u00e9e suivante. Ariane Ascaride n&rsquo;avait pas trente ans et G\u00e9rard Meylan avait le m\u00eame \u00e2ge. Depuis quarante ans, on les a vus vieillir et c&rsquo;est avec une r\u00e9elle \u00e9motion qu&rsquo;on les revoit si jeunes.<\/p>\n<p><em>Rouge Midi<\/em> est un film d&rsquo;une \u00e9tonnante ambition pour un r\u00e9alisateur encore si inexp\u00e9riment\u00e9. Il s&rsquo;agit de brosser l&rsquo;histoire d&rsquo;une famille marseillaise sur quatre g\u00e9n\u00e9rations des ann\u00e9es vingt aux ann\u00e9es quatre-vingts. On sent percer les deux arguments \u00f4 combien politiques de cette fresque : Marseille est une terre d&rsquo;immigration qui s&rsquo;est enrichie de l&rsquo;apport de ces nouveaux venus, l&rsquo;histoire de la cit\u00e9 phoc\u00e9enne est celle des luttes syndicales qu&rsquo;elle a v\u00e9cues.<\/p>\n<p>Robert Gu\u00e9diguian plonge dans ses souvenirs comme Fellini dans <em>Amarcord<\/em> en ressuscitant le vieux Marseille de ses parents ou celui qu&rsquo;il a connu, tout gamin, dans les ann\u00e9es cinquante. Comme la totalit\u00e9 des films qu&rsquo;il tournera ensuite, <em>Rouge Midi<\/em> est une d\u00e9claration d&rsquo;amour \u00e0 sa ville natale.<\/p>\n<p>La limite de ce film est son manque de moyens. Pour tourner pareille fresque, qui aurait peut-\u00eatre \u00e9t\u00e9 plus adapt\u00e9e au format d&rsquo;une s\u00e9rie, il aurait fallu un budget autrement plus important qui aurait permis des reconstitutions plus impressionnantes que celles, bien amateuristes, qu&rsquo;on nous donne \u00e0 voir. On aimerait sentir le grand vent de l&rsquo;Histoire, les gr\u00e8ves du Front populaire, la d\u00e9b\u00e2cle de l&rsquo;Occupation, la liesse de la Lib\u00e9ration ; mais h\u00e9las, on ne voit rien de tout cela et on se limite bien vite \u00e0 une succession de sayn\u00e8tes intimistes dans lesquelles, faute de transitions et de rep\u00e8res chronologiques, on finit par se perdre.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=CI5A4sYf-ag\">Un extrait<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rouge Midi raconte l&rsquo;histoire d&rsquo;une famille italienne arriv\u00e9e par le train \u00e0 L&rsquo;Estaque dans la banlieue de Marseille dans les ann\u00e9es vingt et de sa descendance sur quatre g\u00e9n\u00e9rations. Leur fille Maggiorina (Ariane Ascaride), employ\u00e9e \u00e0 la cimenterie, rencontrera J\u00e9r\u00f4me (G\u00e9rard Meylan), un chauffeur de ma\u00eetre, et traversera avec lui le Front populaire et l&rsquo;Occupation. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-26029","post","type-post","status-publish","format-standard","hentry","category-films-anciens"],"_links":{"self":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/26029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/comments?post=26029"}],"version-history":[{"count":7,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/26029\/revisions"}],"predecessor-version":[{"id":26036,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/posts\/26029\/revisions\/26036"}],"wp:attachment":[{"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/media?parent=26029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/categories?post=26029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/un-film-un-jour.com\/index.php\/wp-json\/wp\/v2\/tags?post=26029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}